{"id":17,"count":1,"description":"","link":"https:\/\/design.sproutui.com\/elementor\/category\/style\/","name":"style","slug":"style","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}