{"id":11932,"date":"2024-08-15T09:50:19","date_gmt":"2024-08-15T09:50:19","guid":{"rendered":"https:\/\/design.sproutui.com\/elementor\/?page_id=11932"},"modified":"2026-04-23T09:03:59","modified_gmt":"2026-04-23T09:03:59","slug":"layout-36","status":"publish","type":"page","link":"https:\/\/design.sproutui.com\/elementor\/why-choose-us\/layout-36\/","title":{"rendered":"Layout-36"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11932\" class=\"elementor elementor-11932\">\n\t\t\t\t<div class=\"plus-widget-inner-wrap tp-standard-gsap elementor-element elementor-element-ef7837f e-flex e-con-boxed e-con e-parent\"  data-tp_gsap_control='{&quot;name&quot;:&quot;Grid-layout Animation&quot;,&quot;_id&quot;:&quot;adc135a&quot;,&quot;tp_stagger&quot;:&quot;yes&quot;,&quot;tp_delay&quot;:&quot;0.3&quot;,&quot;tp_gsap_trigger&quot;:&quot;tp_on_scroll&quot;,&quot;tp_duration&quot;:1.5,&quot;tp_fade_offset&quot;:50,&quot;tp_ani_type&quot;:&quot;tp_fade&quot;,&quot;tp_ease&quot;:&quot;power1.out&quot;,&quot;tp_fade_from&quot;:&quot;bottom&quot;,&quot;tp_stagger_target&quot;:&quot;container&quot;,&quot;tp_stagger_depth&quot;:&quot;child&quot;,&quot;tp_repeat&quot;:&quot;label_off&quot;}'=\"\" data-id=\"ef7837f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;plus_gsap_animation_type&quot;:&quot;tp_global&quot;,&quot;tp_select_global_animation&quot;:&quot;adc135a&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3ee3fdf5 e-con-full e-flex e-con e-child\" data-id=\"3ee3fdf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;plus_gsap_animation_type&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"plus-widget-inner-wrap tp-standard-gsap elementor-element elementor-element-779e3238 text-left elementor-widget elementor-widget-tp-heading-title\" data-tp_gsap_control=\"{&quot;tp_animation_type&quot;:&quot;tp_global&quot;,&quot;tp_trigger&quot;:&quot;&quot;,&quot;tp_delay&quot;:&quot;&quot;,&quot;tp_fade_from&quot;:&quot;&quot;,&quot;tp_duration&quot;:&quot;&quot;,&quot;tp_ease&quot;:&quot;&quot;,&quot;tp_fade_offset&quot;:&quot;&quot;,&quot;tp_stagger&quot;:&quot;&quot;,&quot;tp_stagger_target&quot;:&quot;&quot;,&quot;tp_stagger_depth&quot;:&quot;child&quot;,&quot;tp_repeat&quot;:&quot;&quot;,&quot;tp_ani_type&quot;:&quot;&quot;}\" data-id=\"779e3238\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;plus_gsap_animation_type&quot;:&quot;tp_global&quot;,&quot;tp_select_global_animation&quot;:&quot;838d08a&quot;}\" data-widget_type=\"tp-heading-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"heading heading_style heading_style6a03bfddb4f07 style-2 \"  data-tp-gsap-heading-text=\"\" data-tp-gsap-sub-heading-text=\"\"><div class=\"sub-style \"  ><div class=\"sub-heading\"><h5 class=\"heading-sub-title  \"> Why Choose Us <\/h5><\/div><div class=\"head-title \" > <h2  class=\"heading-title   \"   data-hover=\"Creative and Unique Solutions\">Creative and Unique Solutions<\/h2><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"plus-widget-inner-wrap tp-standard-gsap elementor-element elementor-element-49a24827 elementor-widget elementor-widget-tp-adv-text-block\" data-tp_gsap_control=\"{&quot;name&quot;:&quot;Description Animation&quot;,&quot;_id&quot;:&quot;c45f361&quot;,&quot;tp_gsap_trigger&quot;:&quot;tp_on_scroll&quot;,&quot;tp_delay&quot;:0.15,&quot;tp_duration&quot;:1.5,&quot;tp_fade_offset&quot;:50,&quot;tp_ani_type&quot;:&quot;tp_fade&quot;,&quot;tp_ease&quot;:&quot;power1.out&quot;,&quot;tp_fade_from&quot;:&quot;bottom&quot;,&quot;tp_stagger&quot;:&quot;label_off&quot;,&quot;tp_stagger_target&quot;:&quot;container&quot;,&quot;tp_stagger_depth&quot;:&quot;child&quot;,&quot;tp_repeat&quot;:&quot;label_off&quot;}\" data-id=\"49a24827\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;plus_gsap_animation_type&quot;:&quot;tp_global&quot;,&quot;tp_select_global_animation&quot;:&quot;c45f361&quot;}\" data-widget_type=\"tp-adv-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" data-tp-gsap-textblock=\"\" ><div class=\"text_block_parallax\"><div class=\"pt_plus_adv_text_block \" ><div class=\"text-content-block\">We adhere to the highest standards of quality in all our products and services. From design and development to manufacturing.<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"plus-widget-inner-wrap tp-standard-gsap elementor-element elementor-element-e07c116 e-con-full e-flex e-con e-child\"  data-tp_gsap_control='{&quot;_id&quot;:&quot;152bbd2&quot;,&quot;name&quot;:&quot;Grid-layout Animation-2&quot;,&quot;tp_delay&quot;:&quot;0.3&quot;,&quot;tp_stagger&quot;:&quot;yes&quot;,&quot;tp_stagger_target&quot;:&quot;widget&quot;,&quot;tp_duration&quot;:&quot;1.2&quot;,&quot;tp_gsap_trigger&quot;:&quot;tp_on_scroll&quot;,&quot;tp_fade_offset&quot;:50,&quot;tp_ani_type&quot;:&quot;tp_fade&quot;,&quot;tp_ease&quot;:&quot;power1.out&quot;,&quot;tp_fade_from&quot;:&quot;bottom&quot;,&quot;tp_stagger_depth&quot;:&quot;child&quot;,&quot;tp_repeat&quot;:&quot;label_off&quot;}'=\"\" data-id=\"e07c116\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;plus_gsap_animation_type&quot;:&quot;tp_global&quot;,&quot;tp_select_global_animation&quot;:&quot;152bbd2&quot;}\">\n\t\t<style>.elementor-element-386ab1b .pt_plus_info_box .info-box-inner .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style><style>.elementor-element-386ab1b .pt_plus_info_box .info-box-inner:hover .info-box-bg-box,.elementor-element-386ab1b .pt_plus_info_box .info-box-inner.tp-info-active .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style>\t\t<div class=\"elementor-element elementor-element-386ab1b elementor-widget__width-initial e-transform elementor-widget elementor-widget-tp-info-box\" data-id=\"386ab1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;-8&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;plus_gsap_animation_type&quot;:&quot;none&quot;}\" data-widget_type=\"tp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"info_box6a03662c82a22\" class=\"pt_plus_info_box hover_normal    info_box6a03662c82a22 info-box-style_1      \"  data-id=\"info_box6a03662c82a22\"    dir= data-connection=\"\" data-eventtype=\"\" ><div class=\"post-inner-loop \"><div class=\"info-box-inner content_hover_effect  tp-info-nc\"   ><div class=\"info-box-bg-box   service-border-box\"><div class=\"service-media text-left vertical-center \"><div class=\"m-r-16  \" > <div class=\"service-icon-wrap\"><span class=\" service-icon  icon-squre\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M27.4265 19.8134L29.3332 17.9067L27.4265 16.0001L22.6665 20.7601L11.2398 9.33341L15.9998 4.57341L14.0932 2.66675L12.1865 4.57341L10.2798 2.66675L7.4265 5.52008L5.51984 3.61341L3.61317 5.52008L5.51984 7.42675L2.6665 10.2801L4.57317 12.1867L2.6665 14.0934L4.57317 16.0001L9.33317 11.2401L20.7598 22.6667L15.9998 27.4267L17.9065 29.3334L19.8132 27.4267L21.7198 29.3334L24.5732 26.4801L26.4798 28.3867L28.3865 26.4801L26.4798 24.5734L29.3332 21.7201L27.4265 19.8134Z\" fill=\"white\"><\/path><\/svg><\/span><\/div> <\/div><div class=\"service-content \"><div class=\"service-title \"> Workout <\/div><div class=\"service-desc\"> <p>Our workouts are tailored to accommodate all fitness levels, ensuring that everyone can...<\/p> <\/div><\/div><\/div><div class=\"infobox-overlay-color \"><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style>.elementor-element-4e279d2 .pt_plus_info_box .info-box-inner .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style><style>.elementor-element-4e279d2 .pt_plus_info_box .info-box-inner:hover .info-box-bg-box,.elementor-element-4e279d2 .pt_plus_info_box .info-box-inner.tp-info-active .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style>\t\t<div class=\"elementor-element elementor-element-4e279d2 elementor-widget__width-initial e-transform elementor-widget elementor-widget-tp-info-box\" data-id=\"4e279d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;-8&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;plus_gsap_animation_type&quot;:&quot;none&quot;}\" data-widget_type=\"tp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"info_box6a03662c83d26\" class=\"pt_plus_info_box hover_normal    info_box6a03662c83d26 info-box-style_1      \"  data-id=\"info_box6a03662c83d26\"    dir= data-connection=\"\" data-eventtype=\"\" ><div class=\"post-inner-loop \"><div class=\"info-box-inner content_hover_effect  tp-info-nc\"   ><div class=\"info-box-bg-box   service-border-box\"><div class=\"service-media text-left vertical-center \"><div class=\"m-r-16  \" > <div class=\"service-icon-wrap\"><span class=\" service-icon  icon-squre\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M5.99984 15.3303C7.84079 15.3303 9.33317 13.8379 9.33317 11.997C9.33317 10.156 7.84079 8.66366 5.99984 8.66366C4.15889 8.66366 2.6665 10.156 2.6665 11.997C2.6665 13.8379 4.15889 15.3303 5.99984 15.3303Z\" fill=\"white\"><\/path><path d=\"M11.9998 9.99699C13.8408 9.99699 15.3332 8.50461 15.3332 6.66366C15.3332 4.82271 13.8408 3.33032 11.9998 3.33032C10.1589 3.33032 8.6665 4.82271 8.6665 6.66366C8.6665 8.50461 10.1589 9.99699 11.9998 9.99699Z\" fill=\"white\"><\/path><path d=\"M19.9998 9.99699C21.8408 9.99699 23.3332 8.50461 23.3332 6.66366C23.3332 4.82271 21.8408 3.33032 19.9998 3.33032C18.1589 3.33032 16.6665 4.82271 16.6665 6.66366C16.6665 8.50461 18.1589 9.99699 19.9998 9.99699Z\" fill=\"white\"><\/path><path d=\"M25.9998 15.3303C27.8408 15.3303 29.3332 13.8379 29.3332 11.997C29.3332 10.156 27.8408 8.66366 25.9998 8.66366C24.1589 8.66366 22.6665 10.156 22.6665 11.997C22.6665 13.8379 24.1589 15.3303 25.9998 15.3303Z\" fill=\"white\"><\/path><path d=\"M23.1198 19.1437C21.9598 17.7837 20.9865 16.6237 19.8132 15.2637C19.1998 14.5437 18.4132 13.8237 17.4798 13.5037C17.3332 13.4503 17.1865 13.4103 17.0398 13.3837C16.7065 13.3303 16.3465 13.3303 15.9998 13.3303C15.6532 13.3303 15.2932 13.3303 14.9465 13.397C14.7998 13.4237 14.6532 13.4637 14.5065 13.517C13.5732 13.837 12.7998 14.557 12.1732 15.277C11.0132 16.637 10.0398 17.797 8.8665 19.157C7.11984 20.9037 4.97317 22.837 5.37317 25.5437C5.75984 26.9037 6.73317 28.2503 8.47984 28.637C9.45317 28.837 12.5598 28.0503 15.8665 28.0503H16.1065C19.4132 28.0503 22.5198 28.8237 23.4932 28.637C25.2398 28.2503 26.2132 26.8903 26.5998 25.5437C27.0132 22.8237 24.8665 20.8903 23.1198 19.1437Z\" fill=\"white\"><\/path><\/svg><\/span><\/div> <\/div><div class=\"service-content \"><div class=\"service-title \"> Nutrition <\/div><div class=\"service-desc\"> <p>Our mission is to provide you with valuable resources, expert guidance, and...<\/p> <\/div><\/div><\/div><div class=\"infobox-overlay-color \"><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style>.elementor-element-5942fa5 .pt_plus_info_box .info-box-inner .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style><style>.elementor-element-5942fa5 .pt_plus_info_box .info-box-inner:hover .info-box-bg-box,.elementor-element-5942fa5 .pt_plus_info_box .info-box-inner.tp-info-active .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style>\t\t<div class=\"elementor-element elementor-element-5942fa5 elementor-widget__width-initial e-transform elementor-widget elementor-widget-tp-info-box\" data-id=\"5942fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;-8&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;plus_gsap_animation_type&quot;:&quot;none&quot;}\" data-widget_type=\"tp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"info_box6a03662c84e94\" class=\"pt_plus_info_box hover_normal    info_box6a03662c84e94 info-box-style_1      \"  data-id=\"info_box6a03662c84e94\"    dir= data-connection=\"\" data-eventtype=\"\" ><div class=\"post-inner-loop \"><div class=\"info-box-inner content_hover_effect  tp-info-nc\"   ><div class=\"info-box-bg-box   service-border-box\"><div class=\"service-media text-left vertical-center \"><div class=\"m-r-16  \" > <div class=\"service-icon-wrap\"><span class=\" service-icon  icon-squre\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M28.0002 5.33341C26.5202 4.86675 24.8935 4.66675 23.3335 4.66675C20.7335 4.66675 17.9335 5.20008 16.0002 6.66675C14.0668 5.20008 11.2668 4.66675 8.66683 4.66675C6.06683 4.66675 3.26683 5.20008 1.3335 6.66675V26.2001C1.3335 26.5334 1.66683 26.8667 2.00016 26.8667C2.1335 26.8667 2.20016 26.8001 2.3335 26.8001C4.1335 25.9334 6.7335 25.3334 8.66683 25.3334C11.2668 25.3334 14.0668 25.8667 16.0002 27.3334C17.8002 26.2001 21.0668 25.3334 23.3335 25.3334C25.5335 25.3334 27.8002 25.7334 29.6668 26.7334C29.8002 26.8001 29.8668 26.8001 30.0002 26.8001C30.3335 26.8001 30.6668 26.4667 30.6668 26.1334V6.66675C29.8668 6.06675 29.0002 5.66675 28.0002 5.33341ZM28.0002 23.3334C26.5335 22.8667 24.9335 22.6667 23.3335 22.6667C21.0668 22.6667 17.8002 23.5334 16.0002 24.6667V9.33341C17.8002 8.20008 21.0668 7.33341 23.3335 7.33341C24.9335 7.33341 26.5335 7.53341 28.0002 8.00008V23.3334Z\" fill=\"white\"><\/path><path d=\"M23.3335 12.6667C24.5068 12.6667 25.6402 12.7867 26.6668 13.0134V10.9867C25.6135 10.7867 24.4802 10.6667 23.3335 10.6667C21.0668 10.6667 19.0135 11.0534 17.3335 11.7734V13.9867C18.8402 13.1334 20.9335 12.6667 23.3335 12.6667Z\" fill=\"white\"><\/path><path d=\"M17.3335 15.3201V17.5334C18.8402 16.6801 20.9335 16.2134 23.3335 16.2134C24.5068 16.2134 25.6402 16.3334 26.6668 16.5601V14.5334C25.6135 14.3334 24.4802 14.2134 23.3335 14.2134C21.0668 14.2134 19.0135 14.6134 17.3335 15.3201Z\" fill=\"white\"><\/path><path d=\"M23.3335 17.7734C21.0668 17.7734 19.0135 18.1601 17.3335 18.8801V21.0934C18.8402 20.2401 20.9335 19.7734 23.3335 19.7734C24.5068 19.7734 25.6402 19.8934 26.6668 20.1201V18.0934C25.6135 17.8801 24.4802 17.7734 23.3335 17.7734Z\" fill=\"white\"><\/path><\/svg><\/span><\/div> <\/div><div class=\"service-content \"><div class=\"service-title \"> Progression <\/div><div class=\"service-desc\"> <p>Our focus on progression is what sets us apart and ensures that you experience...<\/p> <\/div><\/div><\/div><div class=\"infobox-overlay-color \"><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style>.elementor-element-0afcfa3 .pt_plus_info_box .info-box-inner .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style><style>.elementor-element-0afcfa3 .pt_plus_info_box .info-box-inner:hover .info-box-bg-box,.elementor-element-0afcfa3 .pt_plus_info_box .info-box-inner.tp-info-active .info-box-bg-box{box-shadow:0px 0px 10px 0px #00000000 !important;}<\/style>\t\t<div class=\"elementor-element elementor-element-0afcfa3 elementor-widget__width-initial e-transform elementor-widget elementor-widget-tp-info-box\" data-id=\"0afcfa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;0&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;-8&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;plus_gsap_animation_type&quot;:&quot;none&quot;}\" data-widget_type=\"tp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"info_box6a03662c8640a\" class=\"pt_plus_info_box hover_normal    info_box6a03662c8640a info-box-style_1      \"  data-id=\"info_box6a03662c8640a\"    dir= data-connection=\"\" data-eventtype=\"\" ><div class=\"post-inner-loop \"><div class=\"info-box-inner content_hover_effect  tp-info-nc\"   ><div class=\"info-box-bg-box   service-border-box\"><div class=\"service-media text-left vertical-center \"><div class=\"m-r-16  \" > <div class=\"service-icon-wrap\"><span class=\" service-icon  icon-squre\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M16 2.66675C17.4667 2.66675 18.6667 3.86675 18.6667 5.33341C18.6667 6.80008 17.4667 8.00008 16 8.00008C14.5333 8.00008 13.3333 6.80008 13.3333 5.33341C13.3333 3.86675 14.5333 2.66675 16 2.66675ZM28 12.0001H20V29.3334H17.3333V21.3334H14.6667V29.3334H12V12.0001H4V9.33342H28V12.0001Z\" fill=\"white\"><\/path><\/svg><\/span><\/div> <\/div><div class=\"service-content \"><div class=\"service-title \"> Self Defence <\/div><div class=\"service-desc\"> <p>Self-defence is not just about physical techniques; In today's world, knowing...<\/p> <\/div><\/div><\/div><div class=\"infobox-overlay-color \"><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Why Choose Us Creative and Unique Solutions We adhere to the highest standards of quality in all our products and services. From design and development to manufacturing. Workout Our workouts are tailored to accommodate all fitness levels, ensuring that everyone can&#8230; Nutrition Our mission is to provide you with valuable resources, expert guidance, and&#8230; Progression [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":50597,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"itsec_x_frame_options":"","footnotes":""},"class_list":["post-11932","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/pages\/11932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/comments?post=11932"}],"version-history":[{"count":87,"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/pages\/11932\/revisions"}],"predecessor-version":[{"id":125577,"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/pages\/11932\/revisions\/125577"}],"up":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/pages\/50597"}],"wp:attachment":[{"href":"https:\/\/design.sproutui.com\/elementor\/wp-json\/wp\/v2\/media?parent=11932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}