{"id":47,"count":3,"description":"","link":"https:\/\/design.sproutui.com\/gutenberg\/category\/hair\/","name":"Hair","slug":"hair","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/categories\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/posts?categories=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}