{"id":11593,"date":"2024-09-16T13:00:49","date_gmt":"2024-09-16T13:00:49","guid":{"rendered":"https:\/\/design.sproutui.com\/gutenberg-nxt\/?page_id=11593"},"modified":"2025-10-03T10:51:27","modified_gmt":"2025-10-03T10:51:27","slug":"layout-98","status":"publish","type":"page","link":"https:\/\/design.sproutui.com\/gutenberg\/services\/layout-98\/","title":{"rendered":"Layout-98"},"content":{"rendered":"<div  class=\"tpgb-container-row tpgb-block-d697_11593     alignfull  tpgb-equal-height  tpgb-container-wide  \" data-id=\"d697_11593\"   data-tpgb-equal-height=\".service-desc,.service-title\" ><div class=\"tpgb-cont-in\">\n<div class=\"tpgb-container-col tpgb-block-d604_11593 \" data-id=\"d604_11593\"   >\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-031b_11593  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><span class=\"tpgb-icon-wrap-text\">1<\/span><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Comprehensive Overview<\/h3><p class=\"service-desc tpgb-trans-linear\">Users can access a comprehensive overview of the services offered&#8230;<\/p><div class=\"infobox-btn-block \"><div class=\"tpgb-adv-button button-style-8 \"><a class=\"button-link-wrap\"  href=\"#\"     >Read More<span class=\"btn-icon button-after\"><i class=\"fas fa-arrow-right \"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-a5c1_11593  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><span class=\"tpgb-icon-wrap-text\">3<\/span><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Resource for Future<\/h3><p class=\"service-desc tpgb-trans-linear\">The Service Matrix serves as a roadmap for future growth&#8230;<\/p><div class=\"infobox-btn-block \"><div class=\"tpgb-adv-button button-style-8 \"><a class=\"button-link-wrap\"  href=\"#\"     >Read More<span class=\"btn-icon button-after\"><i class=\"fas fa-arrow-right \"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-9e1f_11593  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><span class=\"tpgb-icon-wrap-text\">2<\/span><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Comparison and Contrast<\/h3><p class=\"service-desc tpgb-trans-linear\">The Service Matrix enables users to compare and contrast different&#8230;<\/p><div class=\"infobox-btn-block \"><div class=\"tpgb-adv-button button-style-8 \"><a class=\"button-link-wrap\"  href=\"#\"     >Read More<span class=\"btn-icon button-after\"><i class=\"fas fa-arrow-right \"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-d20a_11593  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><span class=\"tpgb-icon-wrap-text\">4<\/span><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Continuous Improvement<\/h3><p class=\"service-desc tpgb-trans-linear\">The Service Matrix is regularly updated and refined to reflect changes&#8230;<\/p><div class=\"infobox-btn-block \"><div class=\"tpgb-adv-button button-style-8 \"><a class=\"button-link-wrap\"  href=\"#\"     >Read More<span class=\"btn-icon button-after\"><i class=\"fas fa-arrow-right \"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-2809_11593 \" data-id=\"2809_11593\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-80d1_11593\"><h2 class=\"pro-heading-inner\">Finding the Right Fit<\/h2><div class=\"pro-paragraph-inner\"><p>Each category represents a distinct area of expertise or focus, with a variety of services tailored to address specific needs and challenges within that domain.<\/p><\/div><\/div>\n\n\n<div class=\"tpgb-plus-button tpgb-relative-block tpgb-block-687b_11593 button-style-10   \"><div class=\"animted-content-inner\"><a href=\"\"   class=\"button-link-wrap     \" role=\"button\" aria-label=\"View All\" data-hover=\"Click Here\" ><span>View All<span class=\"btn-icon   button-after\"><i class=\"fas fa-arrow-right\"><\/i><\/span><\/span><\/a><\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":6124,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tpgb_global_settings":"","itsec_x_frame_options":"","footnotes":""},"class_list":["post-11593","page","type-page","status-publish","hentry"],"tpgb_featured_images":null,"tpgb_post_meta_info":{"get_date":"September 16, 2024","get_modified_date":"October 3, 2025","author_name":"smitposimyth","author_url":"https:\/\/design.sproutui.com\/gutenberg\/author\/smitposimyth\/","author_email":"smit.posimyth@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"","author_lastname":"","user_login":"smitposimyth","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' loading='lazy' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/11593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/comments?post=11593"}],"version-history":[{"count":17,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/11593\/revisions"}],"predecessor-version":[{"id":32835,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/11593\/revisions\/32835"}],"up":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/6124"}],"wp:attachment":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/media?parent=11593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}