{"id":16877,"date":"2024-10-07T05:18:27","date_gmt":"2024-10-07T05:18:27","guid":{"rendered":"https:\/\/design.sproutui.com\/gutenberg-nxt\/?page_id=16877"},"modified":"2025-09-30T07:20:05","modified_gmt":"2025-09-30T07:20:05","slug":"layout-14","status":"publish","type":"page","link":"https:\/\/design.sproutui.com\/gutenberg\/location\/layout-14\/","title":{"rendered":"Location Section-14"},"content":{"rendered":"<div  class=\"tpgb-container-row tpgb-block-3e12_16877     alignfull   tpgb-container-full  \" data-id=\"3e12_16877\"   >\n<div class=\"tpgb-container-col tpgb-block-8d2f_16877 \" data-id=\"8d2f_16877\"   >\n<div class=\"tpgb-google-map tpgb-relative-block tpgb-block-644e_16877 \"><div id=\"gmap-644e_16877\" class=\"tpgb-adv-map\" data-id=\"gmap-644e_16877\" data-map-settings=\"{&quot;places&quot;:[{&quot;address&quot;:&quot;&quot;,&quot;latitude&quot;:40.6884135,&quot;longitude&quot;:-74.3606169,&quot;pin_icon&quot;:&quot;&quot;,&quot;latOrAddr&quot;:&quot;latitude&quot;}],&quot;options&quot;:{&quot;zoom&quot;:15,&quot;scrollwheel&quot;:true,&quot;draggable&quot;:true,&quot;panControl&quot;:true,&quot;zoomControl&quot;:true,&quot;scaleControl&quot;:true,&quot;mapTypeControl&quot;:true,&quot;fullscreenControl&quot;:true,&quot;streetViewControl&quot;:true,&quot;mapTypeId&quot;:&quot;roadmap&quot;}}\" ><\/div><\/div>\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-d4cb_16877 \" data-id=\"d4cb_16877\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-231e_16877\"><h2 class=\"pro-heading-inner\">Discover Our Location<\/h2><div class=\"pro-paragraph-inner\"><p>Whether you&#8217;re visiting us in person or simply want to know where we&#8217;re based, here&#8217;s some helpful information about our location<\/p><\/div><\/div>\n\n\n<div  class=\"tpgb-container-row tpgb-block-0779_16877     alignfull   tpgb-container-full  \" data-id=\"0779_16877\"   >\n<div class=\"tpgb-container-col tpgb-block-c844_16877 \" data-id=\"c844_16877\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-dbc5_16877\"><h4 class=\"pro-heading-inner\">Office Location<\/h4><div class=\"pro-paragraph-inner\"><p>403, Port Washington Road, Canada.<\/p><\/div><\/div>\n\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-1c44_16877 \" data-id=\"1c44_16877\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-afda_16877\"><h4 class=\"pro-heading-inner\">Contact Detail<\/h4><div class=\"pro-paragraph-inner\"><p>+1 800-525-54-589\u2028 +1 300-223-23-752<\/p><\/div><\/div>\n\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-0b61_16877 \" data-id=\"0b61_16877\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-2d31_16877\"><h4 class=\"pro-heading-inner\">Email Address<\/h4><div class=\"pro-paragraph-inner\"><p>info@wdesignkit.com\u2028wdesignkit@gmail.com<\/p><\/div><\/div>\n\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-8f9c_16877 \" data-id=\"8f9c_16877\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-1cac_16877\"><h4 class=\"pro-heading-inner\">Follow Us On<\/h4><\/div>\n\n\n<div class=\"tpgb-social-icons style-16  text-center tpgb-block-5a3b_16877 \"><div class=\"tpgb-social-list \"><div id=\"tooltip6a03ca3fdea3d\" class=\" social-icon-tooltip tp-repeater-item-ndbw style-16 \"  ><div class=\"tpgb-social-loop-inner \"><a class=\"tpgb-icon-link \" href=\"#\" aria-label=\"Facebook\"   ><span class=\"tpgb-social-icn \"><i class=\"fab fa-facebook-f\"><\/i><\/span><\/a><\/div><\/div><div id=\"tooltip6a03ca3fdea6a\" class=\" social-icon-tooltip tp-repeater-item-se7v style-16 \"  ><div class=\"tpgb-social-loop-inner \"><a class=\"tpgb-icon-link \" href=\"#\" aria-label=\"Facebook\"   ><span class=\"tpgb-social-icn \"><i class=\"fab fa-instagram\"><\/i><\/span><\/a><\/div><\/div><div id=\"tooltip6a03ca3fdea75\" class=\" social-icon-tooltip tp-repeater-item-ado5 style-16 \"  ><div class=\"tpgb-social-loop-inner \"><a class=\"tpgb-icon-link \" href=\"#\" aria-label=\"Facebook\"   ><span class=\"tpgb-social-icn \"><i class=\"fab fa-twitter\"><\/i><\/span><\/a><\/div><\/div><div id=\"tooltip6a03ca3fdea7e\" class=\" social-icon-tooltip tp-repeater-item-itqk style-16 \"  ><div class=\"tpgb-social-loop-inner \"><a class=\"tpgb-icon-link \" href=\"#\" aria-label=\"Facebook\"   ><span class=\"tpgb-social-icn \"><i class=\"fab fa-linkedin-in\"><\/i><\/span><\/a><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":14870,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tpgb_global_settings":"","itsec_x_frame_options":"","footnotes":""},"class_list":["post-16877","page","type-page","status-publish","hentry"],"tpgb_featured_images":null,"tpgb_post_meta_info":{"get_date":"October 7, 2024","get_modified_date":"September 30, 2025","author_name":"niravposimyth","author_url":"https:\/\/design.sproutui.com\/gutenberg\/author\/niravposimyth\/","author_email":"nirav.posimyth@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"","author_lastname":"","user_login":"niravposimyth","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/e6fa3d45de75a697d6833408e6e7243c6bd5ca1520567c0e6ba03ee0f44a39f5?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/e6fa3d45de75a697d6833408e6e7243c6bd5ca1520567c0e6ba03ee0f44a39f5?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' loading='lazy' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/e6fa3d45de75a697d6833408e6e7243c6bd5ca1520567c0e6ba03ee0f44a39f5?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/16877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/comments?post=16877"}],"version-history":[{"count":5,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/16877\/revisions"}],"predecessor-version":[{"id":31902,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/16877\/revisions\/31902"}],"up":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/14870"}],"wp:attachment":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/media?parent=16877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}