{"id":18651,"date":"2024-10-18T05:25:57","date_gmt":"2024-10-18T05:25:57","guid":{"rendered":"https:\/\/design.sproutui.com\/gutenberg-nxt\/?page_id=18651"},"modified":"2025-11-14T06:11:08","modified_gmt":"2025-11-14T06:11:08","slug":"layout-11","status":"publish","type":"page","link":"https:\/\/design.sproutui.com\/gutenberg\/portfolio\/layout-11\/","title":{"rendered":"Layout-11"},"content":{"rendered":"<div  class=\"tpgb-container-row tpgb-block-69ea_18651     alignfull   tpgb-container-inline tpgb-container-wide  \" data-id=\"69ea_18651\"   ><div class=\"tpgb-cont-in\">\n<div  class=\"tpgb-container-row tpgb-block-8c3a_18651     alignwide   tpgb-container-inline tpgb-container-wide  \" data-id=\"8c3a_18651\"   ><div class=\"tpgb-cont-in\">\n<div class=\"tpgb-stylist-list tpgb-relative-block tpgb-block-3afe_18651  align-center  \" ><div class=\"tpgb-icon-list-items d-flex-center\"><div id=\"tooltip6a03d543e4615\" class=\"tpgb-icon-list-item tp-repeater-item-0 active\"  ><div class=\"tpgb-icon-list-text\"><p>Portfolio<\/p><\/div><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-tpgb-tp-heading tp-core-heading tpgb-block-efa5_18651\">WDK AI ToolKit Project Highlights<\/h2>\n\n\n\n<div class=\"tpgb-pro-paragraph tpgb-block-d21d_18651\"><div class=\"pro-paragraph-inner\"><p>Explore the groundbreaking projects powered by the WDK AI ToolKit, showcasing its remarkable capabilities and transformative impact across diverse industries.<\/p><\/div><\/div>\n\n<\/div><\/div>\n\n<div  class=\"tpgb-container-row tpgb-block-65cb_18651     alignfull   tpgb-container-inline tpgb-container-full  \" data-id=\"65cb_18651\"   >\n<div  class=\"tpgb-container-row tpgb-block-e64d_18651  tpgb-section-height-min-height tpgb-container-18651    alignfull   tpgb-container-inline tpgb-container-full  \" data-id=\"e64d_18651\"   ><div class=\"tpgb-row-background  \"><div class=\"tpgb-top-layer\"><\/div><\/div>\n\n<h3 class=\"wp-block-tpgb-tp-heading tp-core-heading tpgb-block-2ef9_18651\">High Altitude Wonders<\/h3>\n\n<\/div>\n\n<div  class=\"tpgb-container-row tpgb-block-24d9_18651  tpgb-section-height-min-height tpgb-container-18651    alignfull   tpgb-container-inline tpgb-container-full  \" data-id=\"24d9_18651\"   ><div class=\"tpgb-row-background  \"><div class=\"tpgb-top-layer\"><\/div><\/div>\n\n<h3 class=\"wp-block-tpgb-tp-heading tp-core-heading tpgb-block-3693_18651\">Majestic Mountain Ranges\u200b<\/h3>\n\n<\/div>\n\n<div  class=\"tpgb-container-row tpgb-block-454e_18651  tpgb-section-height-min-height tpgb-container-18651    alignfull   tpgb-container-inline tpgb-container-full  \" data-id=\"454e_18651\"   ><div class=\"tpgb-row-background  \"><div class=\"tpgb-top-layer\"><\/div><\/div>\n\n<h3 class=\"wp-block-tpgb-tp-heading tp-core-heading tpgb-block-06e0_18651\">High Altitude Wonders<\/h3>\n\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":13240,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tpgb_global_settings":"","itsec_x_frame_options":"","footnotes":""},"class_list":["post-18651","page","type-page","status-publish","hentry"],"tpgb_featured_images":null,"tpgb_post_meta_info":{"get_date":"October 18, 2024","get_modified_date":"November 14, 2025","author_name":"smitposimyth","author_url":"https:\/\/design.sproutui.com\/gutenberg\/author\/smitposimyth\/","author_email":"smit.posimyth@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"","author_lastname":"","user_login":"smitposimyth","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' loading='lazy' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/18651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/comments?post=18651"}],"version-history":[{"count":8,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/18651\/revisions"}],"predecessor-version":[{"id":40100,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/18651\/revisions\/40100"}],"up":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/13240"}],"wp:attachment":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/media?parent=18651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}