{"id":4113,"date":"2024-08-14T06:11:41","date_gmt":"2024-08-14T06:11:41","guid":{"rendered":"https:\/\/design.sproutui.com\/gutenberg-nxt\/?page_id=4113"},"modified":"2025-11-13T10:21:48","modified_gmt":"2025-11-13T10:21:48","slug":"layout-21","status":"publish","type":"page","link":"https:\/\/design.sproutui.com\/gutenberg\/why-choose-us\/layout-21\/","title":{"rendered":"Layout-21"},"content":{"rendered":"<div  class=\"tpgb-container-row tpgb-block-00b4_4113     alignfull   tpgb-container-wide  \" data-id=\"00b4_4113\"   ><div class=\"tpgb-cont-in\">\n<div class=\"tpgb-container-col tpgb-block-d896_4113 \" data-id=\"d896_4113\"   >\n\n<div class=\"tpgb-pro-paragraph tpgb-block-13bb_4113\"><h2 class=\"pro-heading-inner\">Creative and Unique Solutions<\/h2><div class=\"pro-paragraph-inner\"><p>We adhere to the highest standards of quality in all our products and services. From design and development to manufacturing.<\/p><\/div><\/div>\n\n<\/div>\n\n<div class=\"tpgb-container-col tpgb-block-f6be_4113 \" data-id=\"f6be_4113\"   >\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-3003_4113  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_float\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><div class=\"tpgb-draw-svg tpgb-trans-linear\" data-id=\"service-svg-3003_4113\" data-type=\"delayed\" data-duration=\"90\" data-stroke=\"rgba(0,0,0,0)\" data-fillColor=\"var(--tpgb-C13)\" data-strokeColorHover=\"\" data-fillColorHover=\"none\" data-fillEnable=\"yes\"><object class=\"info-box-svg\" id=\"service-svg-3003_4113\" type=\"image\/svg+xml\" data=\"https:\/\/design.sproutui.com\/gutenberg\/wp-content\/uploads\/sites\/3\/2025\/09\/WorkOut.svg\" aria-label=\"icon\"><\/object><\/div><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Workout<\/h3><p class=\"service-desc tpgb-trans-linear\">Our workouts are tailored to accommodate all fitness levels.<\/p><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-50d0_4113  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_float\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><div class=\"tpgb-draw-svg tpgb-trans-linear\" data-id=\"service-svg-50d0_4113\" data-type=\"delayed\" data-duration=\"90\" data-stroke=\"rgba(0,0,0,0)\" data-fillColor=\"var(--tpgb-C13)\" data-strokeColorHover=\"\" data-fillColorHover=\"none\" data-fillEnable=\"yes\"><object class=\"info-box-svg\" id=\"service-svg-50d0_4113\" type=\"image\/svg+xml\" data=\"https:\/\/design.sproutui.com\/gutenberg\/wp-content\/uploads\/sites\/3\/2025\/06\/nutrition.svg\" aria-label=\"icon\"><\/object><\/div><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Nutrition<\/h3><p class=\"service-desc tpgb-trans-linear\">Our mission is to provide you with valuable resources.<\/p><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-6674_4113  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_float\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><div class=\"tpgb-draw-svg tpgb-trans-linear\" data-id=\"service-svg-6674_4113\" data-type=\"delayed\" data-duration=\"90\" data-stroke=\"rgba(0,0,0,0)\" data-fillColor=\"var(--tpgb-C13)\" data-strokeColorHover=\"\" data-fillColorHover=\"none\" data-fillEnable=\"yes\"><object class=\"info-box-svg\" id=\"service-svg-6674_4113\" type=\"image\/svg+xml\" data=\"https:\/\/design.sproutui.com\/gutenberg\/wp-content\/uploads\/sites\/3\/2025\/06\/progression.svg\" aria-label=\"icon\"><\/object><\/div><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Progression<\/h3><p class=\"service-desc tpgb-trans-linear\">Our focus on progression is what sets us apart and ensures that.<\/p><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n\n<div class=\"tpgb-infobox tpgb-relative-block tpgb-trans-linear tpgb-block-c8aa_4113  info-box-style-3 \" ><div class=\"post-inner-loop \"><div class=\"info-box-inner tpgb-trans-linear tpgb_cnt_hvr_effect tpgb-relative-block tp-info-nc cnt_hvr_float\"><div class=\"info-box-bg-box tpgb-trans-linear \"><div class=\"text-alignment\"><div class=\"style-3\"><div class=\"info-icon-content\"><div class=\"service-icon-wrap tpgb-trans-linear\"><div class=\"tpgb-draw-svg tpgb-trans-linear\" data-id=\"service-svg-c8aa_4113\" data-type=\"delayed\" data-duration=\"90\" data-stroke=\"rgba(0,0,0,0)\" data-fillColor=\"var(--tpgb-C13)\" data-strokeColorHover=\"\" data-fillColorHover=\"none\" data-fillEnable=\"yes\"><object class=\"info-box-svg\" id=\"service-svg-c8aa_4113\" type=\"image\/svg+xml\" data=\"https:\/\/design.sproutui.com\/gutenberg\/wp-content\/uploads\/sites\/3\/2025\/09\/Accessibility.svg\" aria-label=\"icon\"><\/object><\/div><\/div><\/div><h3 class=\"service-title tpgb-trans-linear\">Self Defense<\/h3><p class=\"service-desc tpgb-trans-linear\">Self-defence is not just about physical techniques.<\/p><\/div><\/div><\/div><div class=\"infobox-overlay-color tpgb-trans-linear\"><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":21290,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tpgb_global_settings":"","itsec_x_frame_options":"","footnotes":""},"class_list":["post-4113","page","type-page","status-publish","hentry"],"tpgb_featured_images":null,"tpgb_post_meta_info":{"get_date":"August 14, 2024","get_modified_date":"November 13, 2025","author_name":"smitposimyth","author_url":"https:\/\/design.sproutui.com\/gutenberg\/author\/smitposimyth\/","author_email":"smit.posimyth@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"","author_lastname":"","user_login":"smitposimyth","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' loading='lazy' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/4e39fd1a325fbe00501185f3c7638410cddae8ea0be012d8a03ae854561e531a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":[],"_links":{"self":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/4113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/comments?post=4113"}],"version-history":[{"count":6,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/4113\/revisions"}],"predecessor-version":[{"id":39858,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/4113\/revisions\/39858"}],"up":[{"embeddable":true,"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/pages\/21290"}],"wp:attachment":[{"href":"https:\/\/design.sproutui.com\/gutenberg\/wp-json\/wp\/v2\/media?parent=4113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}